{"id":7462,"date":"2021-06-15T11:00:00","date_gmt":"2021-06-15T11:00:00","guid":{"rendered":"https:\/\/www.italiaonline.it\/risorse\/google-web-stories-cosa-sono-e-come-funzionano-3977"},"modified":"2025-03-07T09:50:55","modified_gmt":"2025-03-07T08:50:55","slug":"google-web-stories-cosa-sono-e-come-funzionano-3977","status":"publish","type":"post","link":"https:\/\/www.italiaonline.it\/risorse\/google-web-stories-cosa-sono-e-come-funzionano-3977","title":{"rendered":"Cosa sono e come funzionano le Google Web Stories"},"content":{"rendered":"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text el_class=&#8221;breadcumbyoast&#8221;][\/vc_column_text]<div class=\"datapost\"><p>Pubblicato il 15 Giugno 2021 da <a href=\"https:\/\/www.italiaonline.it\/risorse\/author\/redazione-italiaonline\" class=\"author-link\">Redazione Italiaonline<\/a> <\/p><\/div><p class=\"except-articoli\">Le Google Web Stories sono uno strumento innovativo, che offre all'utente un'esperienza unica e dinamica: scopri come funzionano e quando usarle sul blog di Italiaonline.<\/p><div class=\"socialsharediv\"><span class=\"socialshare condividi\">Contenuto:<\/span><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https:\/\/www.italiaonline.it\/risorse\/google-web-stories-cosa-sono-e-come-funzionano-3977\" target=\"_blank\" class=\"socialshare\" title=\"Condividi su Facebook\"><i class=\"icon-default-style fa fa-facebook\" data-color=\"default\"><\/i><\/a><a href=\"https:\/\/api.whatsapp.com\/send?text=https:\/\/www.italiaonline.it\/risorse\/google-web-stories-cosa-sono-e-come-funzionano-3977\" class=\"socialshare\" target=\"_blank\" title=\"Condividi su Whatsapp\"><i class=\"icon-default-style fa fa-whatsapp\" data-color=\"default\"><\/i><\/a><a href=\"https:\/\/twitter.com\/intent\/tweet?text= https:\/\/www.italiaonline.it\/risorse\/google-web-stories-cosa-sono-e-come-funzionano-3977\" target=\"_blank\" class=\"socialshare \" title=\"Condividi su Twitter\"><img decoding=\"async\" class=\"twitterxlogo\" alt=\"logox\" src=\"https:\/\/www.italiaonline.it\/risorse\/wp-content\/uploads\/sites\/12\/2024\/04\/X_logo_2023.svg\"><\/a><a href=\"https:\/\/www.linkedin.com\/shareArticle?mini=true&url=https:\/\/www.italiaonline.it\/risorse\/google-web-stories-cosa-sono-e-come-funzionano-3977&title=&source=italiaonline.it\" target=\"_blank\" class=\"socialshare\" title=\"Condividi su Linkedin\"><i class=\"icon-default-style fa fa-linkedin\" data-color=\"default\"><\/i><\/a><\/div><div class=\"ctapdfdiv\"><div class=\"ctapdfdiva\"><h3>Scarica la guida su come ottimizzare il tuo sito a 360\u00b0<\/h3><\/div><div class=\"ctapdfdivb\"><div class=\"SENDLEAD\"><a class=\"ctaform\" href=\"https:\/\/www.italiaonline.it\/risorse\/guida\/come-ottimizzare-il-tuo-sito-a-360-checklist-completa\">Scarica<\/a><\/div><\/div><\/div><img title=\"Cosa sono e come funzionano le Google Web Stories\"src=\"https:\/\/www.italiaonline.it\/risorse\/wp-content\/uploads\/sites\/12\/2024\/04\/google-web-stories.jpg\">[vc_column_text][\/vc_column_text][vc_column_text]\n<p>Le stories hanno cambiato il modo di fare comunicazione, e questo \u00e8 evidente soprattutto sui social. Hanno aperto la strada a piattaforme che \u2013 le stories \u2013 le hanno nel dna (vedi alla voce TikTok). E sono state notate da Google. \u00c8 cos\u00ec che sono nate le <strong>Google Web Stories<\/strong>. Di cosa si tratta? Come funzionano? Prima di spiegartelo nei dettagli, \u00e8 importante sottolineare come le Google Web Stories siano un\u2019opportunit\u00e0 completamente nuova per gli editori, un modo totalmente innovativo per posizionare i propri contenuti nel traffico di ricerca organico.<\/p>\n<p>Le Web Stories sono effettivamente le versioni sul Web del popolare formato \u201cStorie\u201d che sicuramente avrai visto sui pi\u00f9 celebri social network. Significa dunque che tali contenuti <strong>possono essere ospitati su un sito<\/strong> Web, anzich\u00e9 essere visibili esternamente su un\u2019app che le far\u00e0 scomparire in 24 ore.<\/p>\n<ul class=\"iol-toc\">\n<li><a href=\"#iol-toc-27211001cde8fe39bff9ed07ff71328f\">Cosa sono le Google Web Stories<\/a><\/li>\n<li><a href=\"#iol-toc-937f83efca665f1858038423b1da5672\">Come si creano le Google Web Stories<\/a><\/li>\n<li><a href=\"#iol-toc-57179ac8de18602efc26ca92563e7f37\">Crea prima le storie per i post pi\u00f9 importanti<\/a><\/li>\n<li><a href=\"#iol-toc-06217120d9d323652733d9083a7dcedf\">L\u2019importanza dei link<\/a><\/li>\n<li><a href=\"#iol-toc-3eee5a4105a48a2d2a5e1c0abce9b56a\">Nome e contenuti<\/a><\/li>\n<li><a href=\"#iol-toc-1c9c58a022371601bdbb21c343325b02\">Tracciare le storie web in Google Analytics<\/a><\/li>\n<\/ul>\n<h2 id=\"iol-toc-27211001cde8fe39bff9ed07ff71328f\">Cosa sono le Google Web Stories<\/h2>\n<p>Le Google Web Stories sono incorporamenti AMP brevi, visivi, in stile slideshow, simili alle storie di Facebook o Instagram. Google ha rilasciato il <strong>plugin Web Story<\/strong> ufficiale per WordPress, che aiuta gli editori a crearli in stile drag-and-drop.<\/p>\n<p>Nel corso del loro sviluppo, si sono trasformate da anteprime degli articoli (con la possibilit\u00e0 di indirizzare il traffico verso un determinato link) a vere e proprie storie complete, in grado di raccontare un evento o un determinato fatto.<\/p>\n<p>Queste pagine mini-AMP sono dunque delle presentazioni visive, una serie di immagini o video veloci che un utente pu\u00f2 sfogliare mentre naviga. Quando la storia si conclude, c\u2019\u00e8 un <strong>piccolo invito all\u2019azione <\/strong>(<a href=\"https:\/\/www.italiaonline.it\/risorse\/call-to-action-come-usarla-con-successo-nel-web-marketing-1006\">CTA<\/a>) che pu\u00f2 incoraggiare il pubblico a visitare un determinato sito per ottenere ulteriori informazioni.<\/p>\n<h2 id=\"iol-toc-937f83efca665f1858038423b1da5672\">Come si creano le Google Web Stories<\/h2>\n<p>Se il tuo <a href=\"https:\/\/www.italiaonline.it\/risorse\/pro-e-contro-di-un-sito-creato-con-wordpress-968\">sito \u00e8 basato su WordPress<\/a>, esiste il plugin Web Story ufficiale con interfaccia intuitiva, che include semplici modelli per aiutarti ad iniziare. Una volta creata la storia, il plugin crea un nuovo<strong> post personalizzato<\/strong> per la Storia Web da pubblicare, anche se non verr\u00e0 visualizzato nel feed della tua home page.<\/p>\n<p>Le storie web vivono sulle loro <strong>mini-pagine all\u2019interno di WordPress<\/strong>: non devi incorporarle o inviare del traffico in autonomia verso di esse. Puoi invece utilizzarle per portare pi\u00f9 utenti sul tuo sito, inducendo i lettori a voler leggere i tuoi articoli dopo essersi goduti la storia. Deviare il traffico dal post del blog alla Web Story, invece, \u00e8 sbagliato. O meglio: non \u00e8 funzionale per il raggiungimento de tuoi obiettivi. Per questo motivo \u00e8 sconsigliato incorporare le Google Web Stories negli articoli.<\/p>\n<p><strong>L\u2019obiettivo finale \u00e8 portare migliaia di nuovi visitatori alle Storie web da Google Discover<\/strong>. Quindi, il CTA alla fine di quelle storie dovr\u00e0 invogliare i lettori a visitare il tuo sito, dove i tuoi annunci saranno ottimizzati.<\/p>\n<h2 id=\"iol-toc-57179ac8de18602efc26ca92563e7f37\">Crea prima le storie per i post pi\u00f9 importanti<\/h2>\n<p>Creare prima le storie per i post pi\u00f9 importanti pu\u00f2 sembrare contro intuitivo, perch\u00e9 in genere si tende a classificare gli ultimi contenuti. Ma c\u2019\u00e8 una regola ben precisa che spiega il motivo di questa scelta. Se Google pensa che tu sia un esperto su un particolare argomento, <strong>penser\u00e0 che sei un esperto anche in una Web Story<\/strong> al riguardo. La creazione di Google Web Stories per un articolo importante \u00e8 una sorta d<strong>i annuncio pubblicitario per i tuoi contenuti<\/strong>.<\/p>\n<p>Il motivo per cui lo stai facendo \u00e8 duplice. Innanzitutto, \u00e8 probabile che sarai ben posizionato su quella Web Story. In seconda battuta, la story \u00e8 un nuovo punto in cui Google pu\u00f2 mostrare la tua esperienza. \u00c8 traffico aggiuntivo in <a href=\"https:\/\/www.italiaonline.it\/risorse\/google-discover-come-sfruttarlo-aumentando-traffico-e-visibilita-online-2413\">Google Discover<\/a>, che non avresti ricevuto solo con il tuo ranking organico. E, anche se sei gi\u00e0 al primo posto per un particolare articolo, \u00e8 comunque un guadagno netto di nuovo traffico.<\/p>\n<h2 id=\"iol-toc-06217120d9d323652733d9083a7dcedf\">L\u2019importanza dei link<\/h2>\n<p>Google consiglia di \u201cintegrare profondamente le storie\u201d, creando un <strong>collegamento<\/strong> ad esse dalla tua home page o dalle pagine delle categorie pertinenti. \u00c8 sicuramente un\u2019ottima idea se si hanno homepage statiche o pagine di categoria, dove \u00e8 facile aggiungere contenuti unici. Come avviene per la normale<a href=\"https:\/\/www.italiaonline.it\/risorse\/ricerca-organica-cos-e-e-come-posizionarsi-2590\"> ricerca organica<\/a>, Google cerca infatti di conoscere e di valutare una Storia in base a quali collegamenti esterni e interni puntano ad essa.<\/p>\n<p>Ovviamente, il primo link alla storia dovr\u00e0 essere <strong>inserito nell\u2019articolo<\/strong> a cui quella storia si riferisce. Collegare i due contenuti tra loro aiuter\u00e0 Google a trovare la storia, senza gli svantaggi dell\u2019incorporamento.<\/p>\n<p>Inoltre, Google vuole che gli editori creino una pagina di destinazione separata delle storie web. Una pagina che conterr\u00e0 dunque i collegamenti a tutte le tue storie web, e che sar\u00e0 raggiungibile dalla tua homepage. Il consiglio \u00e8 quello di utilizzare la <strong>pagina di destinazione predefinita<\/strong> che WordPress crea per i tipi di post personalizzati. L\u2019obiettivo \u00e8 mantenere la pagina di destinazione a un click dalla tua home page, motivo per cui le storie web saranno invece a due click di distanza.<\/p>\n<h2 id=\"iol-toc-3eee5a4105a48a2d2a5e1c0abce9b56a\">Nome e contenuti<\/h2>\n<p>Scegli <strong>un nome\/titolo<\/strong> che abbia senso per la parola chiave a cui stai puntando, ma che non sia il nome\/titolo del tuo post. Assicurati che sia attraente per lo spettatore, perch\u00e9 vedr\u00e0 il tuo titolo in \u201cScopri\u201d, sopra l\u2019immagine di copertina della tua storia.<\/p>\n<p>Tieni a mente, inoltre, che l\u2019importanza resta sempre il contenuto. Nei consigli sulle best practice di Google si consigliano <strong>10-20 immagini<\/strong>, col contenuto di ogni diapositiva breve e visivo, basato essenzialmente su immagini e video che andranno a riempire lo schermo. Le storie lunghe solo 2-3 immagini, che costringono il lettore ad andare sul sito Web per qualsiasi informazione utile sull\u2019argomento proposto, non forniscono una buona esperienza utente. Al contrario, le storie che trasmettono informazioni su un post da una diversa angolazione possono essere fantastiche, come un \u201cmaking of\u201d per una ricetta o per la realizzazione di un lavoretto.<\/p>\n<p>Assicurati di <strong>non avere un attributo noindex<\/strong> nella storia, o finirai per impedire a Google di indicizzare la tua pagina. Aggiungi le storie alla tua <strong>sitemap XML<\/strong>, creando una sezione nel tuo indice <a href=\"https:\/\/www.italiaonline.it\/risorse\/sitemap-per-i-motori-di-ricerca-ecco-cosa-c-e-da-sapere-2033\">della sitemap<\/a>, se necessario. Utilizza il \u201cRapporto sulla copertura dell\u2019indice\u201d e il \u201cRapporto Sitemap\u201d di Google Search Console per vedere se Google riesce a trovare le storie web che hai pubblicato. Se desideri poi che vengano visualizzate nei risultati della Ricerca Google desktop, ti consigliamo di aggiungere anche il supporto per le visualizzazioni orizzontali.<\/p>\n<h2 id=\"iol-toc-1c9c58a022371601bdbb21c343325b02\">Tracciare le storie web in Google Analytics<\/h2>\n<p>Il plugin Web Story consente di inserire anche il tuo ID di Google Analytics, e pu\u00f2 inserire automaticamente il codice di monitoraggio corretto per te. L\u2019ideale sarebbe per\u00f2 creare un<strong> profilo Google Analytics separato<\/strong> per tenere traccia delle storie web. Questo perch\u00e9, il traffico verso le Web Stories, non \u00e8 esattamente lo stesso del traffico verso il sito. Le storie sono infatti una specie di annuncio, che viene pubblicato per i propri contenuti all\u2019interno di Google Discover. L\u2019obiettivo delle Web Stories dovrebbe essere quello di convincere gli utenti a fare click sul sito. Non \u00e8 dunque traffico da considerare finch\u00e9 gli utenti non lasciano l\u2019esperienza Web Story e arrivano sul sito web.<\/p>\n<p>Si pu\u00f2 migliorare ulteriormente l\u2019esperienza integrando un <strong>Web Story Player<\/strong> nel proprio sito. Il Web Story Player consente agli utenti di scorrere facilmente tra pi\u00f9 storie, e consente persino di personalizzare quale storia mostrare dopo. Quando le storie sono facili da scoprire, le visualizzazioni e il coinvolgimento possono aumentare, offrendo maggiori opportunit\u00e0 per monetizzare i contenuti.<\/p>\n[\/vc_column_text]<div class=\"posttagdiv\"><span class=\"posttagbutton\">News sito web: articoli e notizie<\/span><\/div><div class=\"socialsharediv\"><span class=\"socialshare condividi\">Contenuto:<\/span><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https:\/\/www.italiaonline.it\/risorse\/google-web-stories-cosa-sono-e-come-funzionano-3977\" target=\"_blank\" class=\"socialshare\" title=\"Condividi su Facebook\"><i class=\"icon-default-style fa fa-facebook\" data-color=\"default\"><\/i><\/a><a href=\"https:\/\/api.whatsapp.com\/send?text=https:\/\/www.italiaonline.it\/risorse\/google-web-stories-cosa-sono-e-come-funzionano-3977\" class=\"socialshare\" target=\"_blank\" title=\"Condividi su Whatsapp\"><i class=\"icon-default-style fa fa-whatsapp\" data-color=\"default\"><\/i><\/a><a href=\"https:\/\/twitter.com\/intent\/tweet?text= https:\/\/www.italiaonline.it\/risorse\/google-web-stories-cosa-sono-e-come-funzionano-3977\" target=\"_blank\" class=\"socialshare \" title=\"Condividi su Twitter\"><img decoding=\"async\" class=\"twitterxlogo\" alt=\"logox\" src=\"https:\/\/www.italiaonline.it\/risorse\/wp-content\/uploads\/sites\/12\/2024\/04\/X_logo_2023.svg\"><\/a><a href=\"https:\/\/www.linkedin.com\/shareArticle?mini=true&url=https:\/\/www.italiaonline.it\/risorse\/google-web-stories-cosa-sono-e-come-funzionano-3977&title=&source=italiaonline.it\" target=\"_blank\" class=\"socialshare\" title=\"Condividi su Linkedin\"><i class=\"icon-default-style fa fa-linkedin\" data-color=\"default\"><\/i><\/a><\/div><div class=\"ctadiv\"><div class=\"ctadiva\"><h3>Realizza il sito migliore per la tua attivit\u00e0 e ottimizzalo per i motori di ricerca<\/h3><\/div><div class=\"ctadivb\"><div class=\"SENDLEAD\"><button class=\"ctaform\" canalelead=\"Canale Online\" siglaprodotto=\"P17\" productname=\"Consulenza Digitale\">Richiedi contatto<\/button><\/div><\/div><\/div>[\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>Le Google Web Stories sono uno strumento innovativo, che offre all&#8217;utente un&#8217;esperienza unica e dinamica: scopri come funzionano e quando usarle sul blog di Italiaonline.<\/p>\n","protected":false},"author":50,"featured_media":7461,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[14,18],"tags":[41],"area-geografica":[],"servizi-acquistati":[],"settore-merceologico":[],"class_list":{"0":"post-7462","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-blog","8":"category-pubblicita-online","9":"tag-sito"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Google Web Stories: cosa sono e come funzionano | Italiaonline<\/title>\n<meta name=\"description\" content=\"Cosa sono e come funzionano le Google Web Stories, lo strumento che offre all&#039;utente un&#039;esperienza unica e dinamica: tutti i dettagli sul blog.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaonline.it\/risorse\/google-web-stories-cosa-sono-e-come-funzionano-3977\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Google Web Stories: cosa sono e come funzionano | Italiaonline\" \/>\n<meta property=\"og:description\" content=\"Cosa sono e come funzionano le Google Web Stories, lo strumento che offre all&#039;utente un&#039;esperienza unica e dinamica: tutti i dettagli sul blog.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaonline.it\/risorse\/google-web-stories-cosa-sono-e-come-funzionano-3977\" \/>\n<meta property=\"og:site_name\" content=\"Blog Italiaonline\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-15T11:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-07T08:50:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaonline.it\/risorse\/wp-content\/uploads\/sites\/12\/2024\/04\/google-web-stories.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione Italiaonline\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Italiaonline\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.italiaonline.it\\\/risorse\\\/google-web-stories-cosa-sono-e-come-funzionano-3977#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.italiaonline.it\\\/risorse\\\/google-web-stories-cosa-sono-e-come-funzionano-3977\"},\"author\":{\"name\":\"Redazione Italiaonline\",\"@id\":\"https:\\\/\\\/www.italiaonline.it\\\/risorse\\\/#\\\/schema\\\/person\\\/9b0e5f3fc87ae9ab9bbdfcf1b418d919\"},\"headline\":\"Cosa sono e come funzionano le Google Web Stories\",\"datePublished\":\"2021-06-15T11:00:00+00:00\",\"dateModified\":\"2025-03-07T08:50:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.italiaonline.it\\\/risorse\\\/google-web-stories-cosa-sono-e-come-funzionano-3977\"},\"wordCount\":1471,\"image\":{\"@id\":\"https:\\\/\\\/www.italiaonline.it\\\/risorse\\\/google-web-stories-cosa-sono-e-come-funzionano-3977#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.italiaonline.it\\\/risorse\\\/wp-content\\\/uploads\\\/sites\\\/12\\\/2024\\\/04\\\/google-web-stories.jpg\",\"keywords\":[\"News sito web: articoli e notizie\"],\"articleSection\":[\"Blog\",\"Pubblicit\u00e0 Online\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.italiaonline.it\\\/risorse\\\/google-web-stories-cosa-sono-e-come-funzionano-3977\",\"url\":\"https:\\\/\\\/www.italiaonline.it\\\/risorse\\\/google-web-stories-cosa-sono-e-come-funzionano-3977\",\"name\":\"Google Web Stories: cosa sono e come funzionano | Italiaonline\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.italiaonline.it\\\/risorse\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.italiaonline.it\\\/risorse\\\/google-web-stories-cosa-sono-e-come-funzionano-3977#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.italiaonline.it\\\/risorse\\\/google-web-stories-cosa-sono-e-come-funzionano-3977#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.italiaonline.it\\\/risorse\\\/wp-content\\\/uploads\\\/sites\\\/12\\\/2024\\\/04\\\/google-web-stories.jpg\",\"datePublished\":\"2021-06-15T11:00:00+00:00\",\"dateModified\":\"2025-03-07T08:50:55+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.italiaonline.it\\\/risorse\\\/#\\\/schema\\\/person\\\/9b0e5f3fc87ae9ab9bbdfcf1b418d919\"},\"description\":\"Cosa sono e come funzionano le Google Web Stories, lo strumento che offre all'utente un'esperienza unica e dinamica: tutti i dettagli sul blog.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.italiaonline.it\\\/risorse\\\/google-web-stories-cosa-sono-e-come-funzionano-3977#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.italiaonline.it\\\/risorse\\\/google-web-stories-cosa-sono-e-come-funzionano-3977\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.italiaonline.it\\\/risorse\\\/google-web-stories-cosa-sono-e-come-funzionano-3977#primaryimage\",\"url\":\"https:\\\/\\\/www.italiaonline.it\\\/risorse\\\/wp-content\\\/uploads\\\/sites\\\/12\\\/2024\\\/04\\\/google-web-stories.jpg\",\"contentUrl\":\"https:\\\/\\\/www.italiaonline.it\\\/risorse\\\/wp-content\\\/uploads\\\/sites\\\/12\\\/2024\\\/04\\\/google-web-stories.jpg\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.italiaonline.it\\\/risorse\\\/google-web-stories-cosa-sono-e-come-funzionano-3977#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.italiaonline.it\\\/risorse\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cosa sono e come funzionano le Google Web Stories\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.italiaonline.it\\\/risorse\\\/#website\",\"url\":\"https:\\\/\\\/www.italiaonline.it\\\/risorse\\\/\",\"name\":\"Blog Italiaonline\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.italiaonline.it\\\/risorse\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.italiaonline.it\\\/risorse\\\/#\\\/schema\\\/person\\\/9b0e5f3fc87ae9ab9bbdfcf1b418d919\",\"name\":\"Redazione Italiaonline\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.italiaonline.it\\\/risorse\\\/wp-content\\\/uploads\\\/sites\\\/12\\\/2025\\\/03\\\/cropped-cropped-cropped-favicon-2-80x80-1.png\",\"url\":\"https:\\\/\\\/www.italiaonline.it\\\/risorse\\\/wp-content\\\/uploads\\\/sites\\\/12\\\/2025\\\/03\\\/cropped-cropped-cropped-favicon-2-80x80-1.png\",\"contentUrl\":\"https:\\\/\\\/www.italiaonline.it\\\/risorse\\\/wp-content\\\/uploads\\\/sites\\\/12\\\/2025\\\/03\\\/cropped-cropped-cropped-favicon-2-80x80-1.png\",\"caption\":\"Redazione Italiaonline\"},\"description\":\"Italiaonline \u00e8 il partner delle imprese italiane nella trasformazione digitale e accompagna oltre 700 grandi imprese, 1.800 enti pubblici e 205 mila piccole e medie imprese. Con 45 sedi e quasi 700 consulenti, offre soluzioni per la presenza online, siti web, e-commerce, pubblicit\u00e0, gestione social e tanto altro. Attraverso le sue piattaforme digitali come PagineGialle, PagineGialle Casa, PagineGialle Shop e PagineBianche connette milioni di clienti con aziende e professionisti. I suoi portali, tra cui Libero e Virgilio, raggiungono oltre 25 milioni di utenti mensili. La concessionaria iOL Advertising supporta i principali operatori economici del Paese, Grandi Aziende e Centri Media, nello sviluppo delle loro campagne di comunicazione digitale.\",\"url\":\"https:\\\/\\\/www.italiaonline.it\\\/risorse\\\/author\\\/redazione-italiaonline\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Google Web Stories: cosa sono e come funzionano | Italiaonline","description":"Cosa sono e come funzionano le Google Web Stories, lo strumento che offre all'utente un'esperienza unica e dinamica: tutti i dettagli sul blog.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaonline.it\/risorse\/google-web-stories-cosa-sono-e-come-funzionano-3977","og_locale":"it_IT","og_type":"article","og_title":"Google Web Stories: cosa sono e come funzionano | Italiaonline","og_description":"Cosa sono e come funzionano le Google Web Stories, lo strumento che offre all'utente un'esperienza unica e dinamica: tutti i dettagli sul blog.","og_url":"https:\/\/www.italiaonline.it\/risorse\/google-web-stories-cosa-sono-e-come-funzionano-3977","og_site_name":"Blog Italiaonline","article_published_time":"2021-06-15T11:00:00+00:00","article_modified_time":"2025-03-07T08:50:55+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/www.italiaonline.it\/risorse\/wp-content\/uploads\/sites\/12\/2024\/04\/google-web-stories.jpg","type":"image\/jpeg"}],"author":"Redazione Italiaonline","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Italiaonline","Tempo di lettura stimato":"8 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.italiaonline.it\/risorse\/google-web-stories-cosa-sono-e-come-funzionano-3977#article","isPartOf":{"@id":"https:\/\/www.italiaonline.it\/risorse\/google-web-stories-cosa-sono-e-come-funzionano-3977"},"author":{"name":"Redazione Italiaonline","@id":"https:\/\/www.italiaonline.it\/risorse\/#\/schema\/person\/9b0e5f3fc87ae9ab9bbdfcf1b418d919"},"headline":"Cosa sono e come funzionano le Google Web Stories","datePublished":"2021-06-15T11:00:00+00:00","dateModified":"2025-03-07T08:50:55+00:00","mainEntityOfPage":{"@id":"https:\/\/www.italiaonline.it\/risorse\/google-web-stories-cosa-sono-e-come-funzionano-3977"},"wordCount":1471,"image":{"@id":"https:\/\/www.italiaonline.it\/risorse\/google-web-stories-cosa-sono-e-come-funzionano-3977#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaonline.it\/risorse\/wp-content\/uploads\/sites\/12\/2024\/04\/google-web-stories.jpg","keywords":["News sito web: articoli e notizie"],"articleSection":["Blog","Pubblicit\u00e0 Online"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.italiaonline.it\/risorse\/google-web-stories-cosa-sono-e-come-funzionano-3977","url":"https:\/\/www.italiaonline.it\/risorse\/google-web-stories-cosa-sono-e-come-funzionano-3977","name":"Google Web Stories: cosa sono e come funzionano | Italiaonline","isPartOf":{"@id":"https:\/\/www.italiaonline.it\/risorse\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaonline.it\/risorse\/google-web-stories-cosa-sono-e-come-funzionano-3977#primaryimage"},"image":{"@id":"https:\/\/www.italiaonline.it\/risorse\/google-web-stories-cosa-sono-e-come-funzionano-3977#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaonline.it\/risorse\/wp-content\/uploads\/sites\/12\/2024\/04\/google-web-stories.jpg","datePublished":"2021-06-15T11:00:00+00:00","dateModified":"2025-03-07T08:50:55+00:00","author":{"@id":"https:\/\/www.italiaonline.it\/risorse\/#\/schema\/person\/9b0e5f3fc87ae9ab9bbdfcf1b418d919"},"description":"Cosa sono e come funzionano le Google Web Stories, lo strumento che offre all'utente un'esperienza unica e dinamica: tutti i dettagli sul blog.","breadcrumb":{"@id":"https:\/\/www.italiaonline.it\/risorse\/google-web-stories-cosa-sono-e-come-funzionano-3977#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaonline.it\/risorse\/google-web-stories-cosa-sono-e-come-funzionano-3977"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaonline.it\/risorse\/google-web-stories-cosa-sono-e-come-funzionano-3977#primaryimage","url":"https:\/\/www.italiaonline.it\/risorse\/wp-content\/uploads\/sites\/12\/2024\/04\/google-web-stories.jpg","contentUrl":"https:\/\/www.italiaonline.it\/risorse\/wp-content\/uploads\/sites\/12\/2024\/04\/google-web-stories.jpg","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaonline.it\/risorse\/google-web-stories-cosa-sono-e-come-funzionano-3977#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaonline.it\/risorse\/"},{"@type":"ListItem","position":2,"name":"Cosa sono e come funzionano le Google Web Stories"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaonline.it\/risorse\/#website","url":"https:\/\/www.italiaonline.it\/risorse\/","name":"Blog Italiaonline","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaonline.it\/risorse\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaonline.it\/risorse\/#\/schema\/person\/9b0e5f3fc87ae9ab9bbdfcf1b418d919","name":"Redazione Italiaonline","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaonline.it\/risorse\/wp-content\/uploads\/sites\/12\/2025\/03\/cropped-cropped-cropped-favicon-2-80x80-1.png","url":"https:\/\/www.italiaonline.it\/risorse\/wp-content\/uploads\/sites\/12\/2025\/03\/cropped-cropped-cropped-favicon-2-80x80-1.png","contentUrl":"https:\/\/www.italiaonline.it\/risorse\/wp-content\/uploads\/sites\/12\/2025\/03\/cropped-cropped-cropped-favicon-2-80x80-1.png","caption":"Redazione Italiaonline"},"description":"Italiaonline \u00e8 il partner delle imprese italiane nella trasformazione digitale e accompagna oltre 700 grandi imprese, 1.800 enti pubblici e 205 mila piccole e medie imprese. Con 45 sedi e quasi 700 consulenti, offre soluzioni per la presenza online, siti web, e-commerce, pubblicit\u00e0, gestione social e tanto altro. Attraverso le sue piattaforme digitali come PagineGialle, PagineGialle Casa, PagineGialle Shop e PagineBianche connette milioni di clienti con aziende e professionisti. I suoi portali, tra cui Libero e Virgilio, raggiungono oltre 25 milioni di utenti mensili. La concessionaria iOL Advertising supporta i principali operatori economici del Paese, Grandi Aziende e Centri Media, nello sviluppo delle loro campagne di comunicazione digitale.","url":"https:\/\/www.italiaonline.it\/risorse\/author\/redazione-italiaonline"}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/www.italiaonline.it\/risorse\/wp-json\/wp\/v2\/posts\/7462","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.italiaonline.it\/risorse\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaonline.it\/risorse\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaonline.it\/risorse\/wp-json\/wp\/v2\/users\/50"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaonline.it\/risorse\/wp-json\/wp\/v2\/comments?post=7462"}],"version-history":[{"count":1,"href":"https:\/\/www.italiaonline.it\/risorse\/wp-json\/wp\/v2\/posts\/7462\/revisions"}],"predecessor-version":[{"id":13388,"href":"https:\/\/www.italiaonline.it\/risorse\/wp-json\/wp\/v2\/posts\/7462\/revisions\/13388"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaonline.it\/risorse\/wp-json\/wp\/v2\/media\/7461"}],"wp:attachment":[{"href":"https:\/\/www.italiaonline.it\/risorse\/wp-json\/wp\/v2\/media?parent=7462"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaonline.it\/risorse\/wp-json\/wp\/v2\/categories?post=7462"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaonline.it\/risorse\/wp-json\/wp\/v2\/tags?post=7462"},{"taxonomy":"area-geografica","embeddable":true,"href":"https:\/\/www.italiaonline.it\/risorse\/wp-json\/wp\/v2\/area-geografica?post=7462"},{"taxonomy":"servizi-acquistati","embeddable":true,"href":"https:\/\/www.italiaonline.it\/risorse\/wp-json\/wp\/v2\/servizi-acquistati?post=7462"},{"taxonomy":"settore-merceologico","embeddable":true,"href":"https:\/\/www.italiaonline.it\/risorse\/wp-json\/wp\/v2\/settore-merceologico?post=7462"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}