{"id":3050,"date":"2021-09-22T06:00:00","date_gmt":"2021-09-22T06:00:00","guid":{"rendered":"https:\/\/www.italiaonline.it\/risorse\/google-ads-come-selezionare-parole-chiave-efficaci-4416"},"modified":"2025-03-07T09:36:20","modified_gmt":"2025-03-07T08:36:20","slug":"google-ads-come-selezionare-parole-chiave-efficaci-4416","status":"publish","type":"post","link":"https:\/\/www.italiaonline.it\/risorse\/google-ads-come-selezionare-parole-chiave-efficaci-4416","title":{"rendered":"Google Ads: come selezionare parole chiave efficaci"},"content":{"rendered":"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text el_class=&#8221;breadcumbyoast&#8221;][\/vc_column_text]<div class=\"datapost\"><p>Pubblicato il 22 Settembre 2021 da <a href=\"https:\/\/www.italiaonline.it\/risorse\/author\/redazione-italiaonline\" class=\"author-link\">Redazione Italiaonline<\/a> <\/p><\/div><p class=\"except-articoli\">Se devi realizzare una campagna Google Ads sai quanto la scelta delle keyword influenza l\u2019efficacia delle tue promozioni online. Ecco come selezionare le parole chiave<\/p><div class=\"socialsharediv\"><span class=\"socialshare condividi\">Contenuto:<\/span><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https:\/\/www.italiaonline.it\/risorse\/google-ads-come-selezionare-parole-chiave-efficaci-4416\" target=\"_blank\" class=\"socialshare\" title=\"Condividi su Facebook\"><i class=\"icon-default-style fa fa-facebook\" data-color=\"default\"><\/i><\/a><a href=\"https:\/\/api.whatsapp.com\/send?text=https:\/\/www.italiaonline.it\/risorse\/google-ads-come-selezionare-parole-chiave-efficaci-4416\" class=\"socialshare\" target=\"_blank\" title=\"Condividi su Whatsapp\"><i class=\"icon-default-style fa fa-whatsapp\" data-color=\"default\"><\/i><\/a><a href=\"https:\/\/twitter.com\/intent\/tweet?text= https:\/\/www.italiaonline.it\/risorse\/google-ads-come-selezionare-parole-chiave-efficaci-4416\" target=\"_blank\" class=\"socialshare \" title=\"Condividi su Twitter\"><img decoding=\"async\" class=\"twitterxlogo\" alt=\"logox\" src=\"https:\/\/www.italiaonline.it\/risorse\/wp-content\/uploads\/sites\/12\/2024\/04\/X_logo_2023.svg\"><\/a><a href=\"https:\/\/www.linkedin.com\/shareArticle?mini=true&url=https:\/\/www.italiaonline.it\/risorse\/google-ads-come-selezionare-parole-chiave-efficaci-4416&title=&source=italiaonline.it\" target=\"_blank\" class=\"socialshare\" title=\"Condividi su Linkedin\"><i class=\"icon-default-style fa fa-linkedin\" data-color=\"default\"><\/i><\/a><\/div><div class=\"ctapdfdiv\"><div class=\"ctapdfdiva\"><h3>Scarica la guida su come e perch\u00e9 fare pubblicit\u00e0 online<\/h3><\/div><div class=\"ctapdfdivb\"><div class=\"SENDLEAD\"><a class=\"ctaform\" href=\"https:\/\/www.italiaonline.it\/risorse\/guida\/come-e-perche-fare-pubblicita-online\">Scarica<\/a><\/div><\/div><\/div><img title=\"Google Ads: come selezionare parole chiave efficaci\"src=\"https:\/\/www.italiaonline.it\/risorse\/wp-content\/uploads\/sites\/12\/2024\/04\/google-ads.jpg\">[vc_column_text][\/vc_column_text][vc_column_text]\n<p>Gestisci un sito web, un blog o un e-commerce e vorresti promuoverlo online per raggiungere la fetta di pubblico sempre maggiore e<strong> incrementare le tue possibilit\u00e0 di conversione<\/strong>? Probabilmente ti sarai dedicato alla SEO, ossia al miglioramento del tuo posizionamento organico sui motori di ricerca, ma avrai ipotizzato l\u2019idea di <strong>dare una spinta alla tua crescita in rete<\/strong> attraverso campagne a pagamento come quelle messe a disposizione da Google Ads.<\/p>\n<p>Il programma di advertising di Google ti consente di creare campagne di marketing e annunci mirati per pubblicizzare la tua offerta, con <strong>modalit\u00e0 pay-per-click<\/strong> (PPC). Secondo quanto afferma l\u2019azienda stessa, una campagna Google ben progettata e realizzata con cura pu\u00f2 raggiungere fino al 90% degli utenti internet: considerando inoltre che, nel 2021, sono <strong>pi\u00f9 di 4 miliardi e mezzo le persone che accedono alla rete<\/strong> (oltre 50 milioni solo in Italia), l\u2019audience potenziale di un annuncio sponsorizzato su questo search engine pu\u00f2 portare a risultati decisamente soddisfacenti (dati We Are Social 2021).<\/p>\n<p>Il concetto fondamentale su cui si basano le campagne Google, come molte altre strategie di marketing online, sono le parole chiave: anche gli annunci Google Ads ruotano infatti attorno all\u2019<strong>accurata selezione delle migliori keyword<\/strong>, che intercettino le ricerche degli utenti in target e ottimizzino i tuoi investimenti pubblicitari. La ricerca keyword su Google \u00e8 facilitata dagli strumenti messi a disposizione dalla piattaforma stessa, ma come scegliere le parole chiave giuste per la tua campagna Google Ads?<\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_84 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<span class=\"ez-toc-title-toggle\"><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.italiaonline.it\/risorse\/google-ads-come-selezionare-parole-chiave-efficaci-4416\/#Come_scegliere_le_keyword_su_Google_Ads\" >Come scegliere le keyword su Google Ads<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.italiaonline.it\/risorse\/google-ads-come-selezionare-parole-chiave-efficaci-4416\/#Conoscere_il_tuo_pubblico_target\" >Conoscere il tuo pubblico target<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.italiaonline.it\/risorse\/google-ads-come-selezionare-parole-chiave-efficaci-4416\/#Scegliere_se_essere_specifico_o_generico\" >Scegliere se essere specifico o generico<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/www.italiaonline.it\/risorse\/google-ads-come-selezionare-parole-chiave-efficaci-4416\/#Utilizzare_la_corrispondenza_per_affinare_i_tuoi_annunci\" >Utilizzare la corrispondenza per affinare i tuoi annunci<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/www.italiaonline.it\/risorse\/google-ads-come-selezionare-parole-chiave-efficaci-4416\/#Scegli_un_numero_bilanciato_di_keywords\" >Scegli un numero bilanciato di keywords<\/a><\/li><\/ul><\/nav><\/div>\n<h2 id=\"iol-toc-0f1211f5746d21639987d69cee4be5c4\"><span class=\"ez-toc-section\" id=\"Come_scegliere_le_keyword_su_Google_Ads\"><\/span><strong>Come scegliere le keyword su Google Ads <\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Individuare le parole chiave corrette per la tua campagna di advertising sul motore di ricerca ti permette di <strong>mostrare gli annunci alla fascia di pubblico pi\u00f9 idonea<\/strong>, ossia agli utenti realmente in target con i tuoi prodotti o servizi: trattandosi di <a href=\"https:\/\/www.italiaonline.it\/risorse\/campagne-ppc-perche-sono-cosi-importanti-per-un-business-2159\">pubblicit\u00e0 PPC<\/a>, sbagliare keyword potrebbe di fatto disperdere il budget che hai messo a disposizione della promozione digitale. Esistono alcune regole di base per scegliere al meglio le tue parole chiave.<\/p>\n<h2 id=\"iol-toc-c6ec060d9accb900b979a76922773613\"><span class=\"ez-toc-section\" id=\"Conoscere_il_tuo_pubblico_target\"><\/span><strong>Conoscere il tuo pubblico target<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Questa regola aurea del marketing di applica anche alle campagne Google Ads: avere chiare<strong> le caratteristiche delle tue buyer personas<\/strong> ti aiuta enormemente e definire quali termini di ricerca esse userebbero per trovare ci\u00f2 che cercano online e, di conseguenza, a impostare il tuo piano di marketing. Individua <a href=\"https:\/\/www.italiaonline.it\/risorse\/cos-e-una-query-e-come-si-effettua-1237\">le query basilari<\/a> che il tuo pubblico tende a usare, anche attraverso l\u2019analisi delle statistiche estrapolate da altri strumenti Google come Google Analytics e Google Search Console, e cerca di ampliarle con termini di ricerca pi\u00f9 specifici o che includano anche il tuo marchio o i tuoi modelli.<\/p>\n<h2 id=\"iol-toc-00a981c5956b3a6b73f14e265f7f54fe\"><span class=\"ez-toc-section\" id=\"Scegliere_se_essere_specifico_o_generico\"><\/span><strong>Scegliere se essere specifico o generico<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Usare parole chiave generiche pu\u00f2 aiutarti a intercettare un pubblico di utenti ampio ma che potrebbe non essere realmente interessato alla tua specifica offerta: il rischio in questo caso \u00e8 di disperdere budget lasciando che il tuo annuncio appaia in <strong>ricerche non legate al tuo business <\/strong>o che venga mostrato a utenti online alla ricerca di qualcosa di differente.<\/p>\n<p>Al contrario, <a href=\"https:\/\/www.italiaonline.it\/risorse\/come-fare-keyword-research-per-la-local-seo-4296\">scegliere keyword<\/a> specifiche e mirate \u00e8 la strategia migliore per ottimizzare l\u2019investimento in Ads e trarre il massimo dai tuoi annunci: usare parole chiave ben definite, o <strong>keyword a coda lunga<\/strong>, aiuta le tue inserzioni ad apparire solamente in relazione a query di ricerca correlate in maniera chiara alla tua attivit\u00e0. L\u2019ampiezza del pubblico raggiungibile ovviamente in questo caso viene ridotta, ma avrai maggiori opportunit\u00e0 di<strong> pagare per un click da parte di un utente davvero interessato<\/strong> e potenzialmente profittevole.<\/p>\n<h2 id=\"iol-toc-abd792a1d267720b8b3a505d708cbe8d\"><span class=\"ez-toc-section\" id=\"Utilizzare_la_corrispondenza_per_affinare_i_tuoi_annunci\"><\/span><strong>Utilizzare la corrispondenza per affinare i tuoi annunci<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Perch\u00e9 una campagna Google Search si attivi, l\u2019utente in navigazione dovr\u00e0 digitare una o una keywords specifiche, scelte da chi ha creato l\u2019annuncio. Per evitare per\u00f2 che gli annunci vengano proposti anche quando i naviganti hanno intenti di ricerca differenti da quello scelto dall\u2019inserzionista, <strong>\u00e8 possibile affinare la selezione delle parole chiave <\/strong>attraverso il sistema della corrispondenza. Quali sono le tipologie di corrispondenza che<a href=\"https:\/\/www.italiaonline.it\/risorse\/come-investire-il-proprio-budget-in-una-campagna-google-ads-3489\"> Google Ads<\/a> propone?<\/p>\n<ul>\n<li><strong>Corrispondenza generica<\/strong>, ossia l\u2019alternativa adottata in automatico dalla piattaforma, che fa attivare l\u2019inserzione per tutte le ricerche, anche quelle che includono sinonimi, correlate o errori ortografici<\/li>\n<li><strong>Corrispondenza esatta<\/strong>, ovvero la scelta che attiva gli annunci per ricerche che hanno il significato o l\u2019intento esatto della parola chiave e che offre il massimo del controllo sulla platea che vedr\u00e0 l\u2019annuncio<\/li>\n<li><strong>Corrispondenza a frase<\/strong>, cio\u00e8 un\u2019opzione pi\u00f9 specifica della corrispondenza generica, ma maggiormente flessibile rispetto della corrispondenza esatta, che permette ai tuoi annunci di comparire per ricerche relative a una frase o alle sue varianti, precedute o seguite da una o pi\u00f9 parole<\/li>\n<\/ul>\n<p>Inoltre, grazie alla <strong>corrispondenza inversa<\/strong> \u00e8 possibile far s\u00ec che gli annunci non vengano attivati per le keywords che l\u2019inserzionista gi\u00e0 sa che sarebbero inutili o dispersive per il fine della campagna. Sulla rete Display invece, di default le parole chiave vengono considerate a corrispondenza generica.<\/p>\n<h2 id=\"iol-toc-7db099f62a7c5c7cde32073a37718c87\"><span class=\"ez-toc-section\" id=\"Scegli_un_numero_bilanciato_di_keywords\"><\/span><strong>Scegli un numero bilanciato di keywords<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Oltre a capire come individuare le parole chiave per Google Ads, \u00e8 anche bene sapere <strong>quante keyword inserire nei tuoi annunci<\/strong>: il numero consigliato non supera in genere le 20 parole per ogni gruppo di annunci. Anche se in realt\u00e0 \u00e8 possibile inserire molte pi\u00f9 parole chiave nelle tue campagne, dovrai sempre ponderare bene la tua scelta considerando le possibili attivazioni di annunci poco fruttuose e, specialmente se utilizzi la corrispondenza generica, l\u2019ampia gamma di sinonimi, correlate e varianti che potranno essere automaticamente incluse.<\/p>\n<p>Impostare un gruppo di annunci ben definito ti permette di <strong>creare un set di keyword abbastanza specifico<\/strong> da essere davvero in linea sia con gli annunci, che con le eventuali <a href=\"https:\/\/www.italiaonline.it\/risorse\/tutti-i-segreti-di-una-landing-page-vincente-per-google-ads-1786\">landing page<\/a> degli stessi, ricordando che il viaggio del potenziale cliente dovr\u00e0 essere quanto pi\u00f9 coerente, fluido e convincente possibile.<\/p>\n[\/vc_column_text]<div class=\"posttagdiv\"><span class=\"posttagbutton\">Articoli e news sulla pubblicit\u00e0 online<\/span><\/div><div class=\"socialsharediv\"><span class=\"socialshare condividi\">Contenuto:<\/span><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https:\/\/www.italiaonline.it\/risorse\/google-ads-come-selezionare-parole-chiave-efficaci-4416\" target=\"_blank\" class=\"socialshare\" title=\"Condividi su Facebook\"><i class=\"icon-default-style fa fa-facebook\" data-color=\"default\"><\/i><\/a><a href=\"https:\/\/api.whatsapp.com\/send?text=https:\/\/www.italiaonline.it\/risorse\/google-ads-come-selezionare-parole-chiave-efficaci-4416\" class=\"socialshare\" target=\"_blank\" title=\"Condividi su Whatsapp\"><i class=\"icon-default-style fa fa-whatsapp\" data-color=\"default\"><\/i><\/a><a href=\"https:\/\/twitter.com\/intent\/tweet?text= https:\/\/www.italiaonline.it\/risorse\/google-ads-come-selezionare-parole-chiave-efficaci-4416\" target=\"_blank\" class=\"socialshare \" title=\"Condividi su Twitter\"><img decoding=\"async\" class=\"twitterxlogo\" alt=\"logox\" src=\"https:\/\/www.italiaonline.it\/risorse\/wp-content\/uploads\/sites\/12\/2024\/04\/X_logo_2023.svg\"><\/a><a href=\"https:\/\/www.linkedin.com\/shareArticle?mini=true&url=https:\/\/www.italiaonline.it\/risorse\/google-ads-come-selezionare-parole-chiave-efficaci-4416&title=&source=italiaonline.it\" target=\"_blank\" class=\"socialshare\" title=\"Condividi su Linkedin\"><i class=\"icon-default-style fa fa-linkedin\" data-color=\"default\"><\/i><\/a><\/div><div class=\"ctadiv\"><div class=\"ctadiva\"><h3>Crea la tua campagna pubblicitaria online!<\/h3><\/div><div class=\"ctadivb\"><div class=\"SENDLEAD\"><button class=\"ctaform\" canalelead=\"Canale Online\" siglaprodotto=\"Pubblicit\u00e0 online-P06\" productname=\"Pubblicit\u00e0 online\">RICHIEDI CONTATTO<\/button><\/div><\/div><\/div>[\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>Se devi realizzare una campagna Google Ads sai quanto la scelta delle keyword influenza l\u2019efficacia delle tue promozioni online. Ecco come selezionare le parole chiave<\/p>\n","protected":false},"author":50,"featured_media":1101,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[14,18],"tags":[46],"area-geografica":[],"servizi-acquistati":[],"settore-merceologico":[],"class_list":{"0":"post-3050","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-blog","8":"category-pubblicita-online","9":"tag-pubblicita-online"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Google Ads: come scegliere le parole chiave giuste | Italiaonline<\/title>\n<meta name=\"description\" content=\"Devi creare una campagna Google Ads? Scegliere le parole chiave giuste per il tuo annuncio \u00e8 fondamentale. Scopri di pi\u00f9 su Italiaonline.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaonline.it\/risorse\/google-ads-come-selezionare-parole-chiave-efficaci-4416\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Google Ads: come scegliere le parole chiave giuste | Italiaonline\" \/>\n<meta property=\"og:description\" content=\"Devi creare una campagna Google Ads? Scegliere le parole chiave giuste per il tuo annuncio \u00e8 fondamentale. Scopri di pi\u00f9 su Italiaonline.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaonline.it\/risorse\/google-ads-come-selezionare-parole-chiave-efficaci-4416\" \/>\n<meta property=\"og:site_name\" content=\"Blog Italiaonline\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-22T06:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-07T08:36:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaonline.it\/risorse\/wp-content\/uploads\/sites\/12\/2024\/04\/google-ads.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1217\" \/>\n\t<meta property=\"og:image:height\" content=\"694\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione Italiaonline\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Italiaonline\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.italiaonline.it\\\/risorse\\\/google-ads-come-selezionare-parole-chiave-efficaci-4416#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.italiaonline.it\\\/risorse\\\/google-ads-come-selezionare-parole-chiave-efficaci-4416\"},\"author\":{\"name\":\"Redazione Italiaonline\",\"@id\":\"https:\\\/\\\/www.italiaonline.it\\\/risorse\\\/#\\\/schema\\\/person\\\/9b0e5f3fc87ae9ab9bbdfcf1b418d919\"},\"headline\":\"Google Ads: come selezionare parole chiave efficaci\",\"datePublished\":\"2021-09-22T06:00:00+00:00\",\"dateModified\":\"2025-03-07T08:36:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.italiaonline.it\\\/risorse\\\/google-ads-come-selezionare-parole-chiave-efficaci-4416\"},\"wordCount\":1156,\"image\":{\"@id\":\"https:\\\/\\\/www.italiaonline.it\\\/risorse\\\/google-ads-come-selezionare-parole-chiave-efficaci-4416#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.italiaonline.it\\\/risorse\\\/wp-content\\\/uploads\\\/sites\\\/12\\\/2024\\\/04\\\/google-ads.jpg\",\"keywords\":[\"Articoli e news sulla pubblicit\u00e0 online\"],\"articleSection\":[\"Blog\",\"Pubblicit\u00e0 Online\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.italiaonline.it\\\/risorse\\\/google-ads-come-selezionare-parole-chiave-efficaci-4416\",\"url\":\"https:\\\/\\\/www.italiaonline.it\\\/risorse\\\/google-ads-come-selezionare-parole-chiave-efficaci-4416\",\"name\":\"Google Ads: come scegliere le parole chiave giuste | Italiaonline\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.italiaonline.it\\\/risorse\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.italiaonline.it\\\/risorse\\\/google-ads-come-selezionare-parole-chiave-efficaci-4416#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.italiaonline.it\\\/risorse\\\/google-ads-come-selezionare-parole-chiave-efficaci-4416#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.italiaonline.it\\\/risorse\\\/wp-content\\\/uploads\\\/sites\\\/12\\\/2024\\\/04\\\/google-ads.jpg\",\"datePublished\":\"2021-09-22T06:00:00+00:00\",\"dateModified\":\"2025-03-07T08:36:20+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.italiaonline.it\\\/risorse\\\/#\\\/schema\\\/person\\\/9b0e5f3fc87ae9ab9bbdfcf1b418d919\"},\"description\":\"Devi creare una campagna Google Ads? Scegliere le parole chiave giuste per il tuo annuncio \u00e8 fondamentale. Scopri di pi\u00f9 su Italiaonline.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.italiaonline.it\\\/risorse\\\/google-ads-come-selezionare-parole-chiave-efficaci-4416#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.italiaonline.it\\\/risorse\\\/google-ads-come-selezionare-parole-chiave-efficaci-4416\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.italiaonline.it\\\/risorse\\\/google-ads-come-selezionare-parole-chiave-efficaci-4416#primaryimage\",\"url\":\"https:\\\/\\\/www.italiaonline.it\\\/risorse\\\/wp-content\\\/uploads\\\/sites\\\/12\\\/2024\\\/04\\\/google-ads.jpg\",\"contentUrl\":\"https:\\\/\\\/www.italiaonline.it\\\/risorse\\\/wp-content\\\/uploads\\\/sites\\\/12\\\/2024\\\/04\\\/google-ads.jpg\",\"width\":1217,\"height\":694},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.italiaonline.it\\\/risorse\\\/google-ads-come-selezionare-parole-chiave-efficaci-4416#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.italiaonline.it\\\/risorse\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Google Ads: come selezionare parole chiave efficaci\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.italiaonline.it\\\/risorse\\\/#website\",\"url\":\"https:\\\/\\\/www.italiaonline.it\\\/risorse\\\/\",\"name\":\"Blog Italiaonline\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.italiaonline.it\\\/risorse\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.italiaonline.it\\\/risorse\\\/#\\\/schema\\\/person\\\/9b0e5f3fc87ae9ab9bbdfcf1b418d919\",\"name\":\"Redazione Italiaonline\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.italiaonline.it\\\/risorse\\\/wp-content\\\/uploads\\\/sites\\\/12\\\/2025\\\/03\\\/cropped-cropped-cropped-favicon-2-80x80-1.png\",\"url\":\"https:\\\/\\\/www.italiaonline.it\\\/risorse\\\/wp-content\\\/uploads\\\/sites\\\/12\\\/2025\\\/03\\\/cropped-cropped-cropped-favicon-2-80x80-1.png\",\"contentUrl\":\"https:\\\/\\\/www.italiaonline.it\\\/risorse\\\/wp-content\\\/uploads\\\/sites\\\/12\\\/2025\\\/03\\\/cropped-cropped-cropped-favicon-2-80x80-1.png\",\"caption\":\"Redazione Italiaonline\"},\"description\":\"Italiaonline \u00e8 il partner delle imprese italiane nella trasformazione digitale e accompagna oltre 700 grandi imprese, 1.800 enti pubblici e 205 mila piccole e medie imprese. Con 45 sedi e quasi 700 consulenti, offre soluzioni per la presenza online, siti web, e-commerce, pubblicit\u00e0, gestione social e tanto altro. Attraverso le sue piattaforme digitali come PagineGialle, PagineGialle Casa, PagineGialle Shop e PagineBianche connette milioni di clienti con aziende e professionisti. I suoi portali, tra cui Libero e Virgilio, raggiungono oltre 25 milioni di utenti mensili. La concessionaria iOL Advertising supporta i principali operatori economici del Paese, Grandi Aziende e Centri Media, nello sviluppo delle loro campagne di comunicazione digitale.\",\"url\":\"https:\\\/\\\/www.italiaonline.it\\\/risorse\\\/author\\\/redazione-italiaonline\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Google Ads: come scegliere le parole chiave giuste | Italiaonline","description":"Devi creare una campagna Google Ads? Scegliere le parole chiave giuste per il tuo annuncio \u00e8 fondamentale. Scopri di pi\u00f9 su Italiaonline.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaonline.it\/risorse\/google-ads-come-selezionare-parole-chiave-efficaci-4416","og_locale":"it_IT","og_type":"article","og_title":"Google Ads: come scegliere le parole chiave giuste | Italiaonline","og_description":"Devi creare una campagna Google Ads? Scegliere le parole chiave giuste per il tuo annuncio \u00e8 fondamentale. Scopri di pi\u00f9 su Italiaonline.","og_url":"https:\/\/www.italiaonline.it\/risorse\/google-ads-come-selezionare-parole-chiave-efficaci-4416","og_site_name":"Blog Italiaonline","article_published_time":"2021-09-22T06:00:00+00:00","article_modified_time":"2025-03-07T08:36:20+00:00","og_image":[{"width":1217,"height":694,"url":"https:\/\/www.italiaonline.it\/risorse\/wp-content\/uploads\/sites\/12\/2024\/04\/google-ads.jpg","type":"image\/jpeg"}],"author":"Redazione Italiaonline","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Italiaonline","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.italiaonline.it\/risorse\/google-ads-come-selezionare-parole-chiave-efficaci-4416#article","isPartOf":{"@id":"https:\/\/www.italiaonline.it\/risorse\/google-ads-come-selezionare-parole-chiave-efficaci-4416"},"author":{"name":"Redazione Italiaonline","@id":"https:\/\/www.italiaonline.it\/risorse\/#\/schema\/person\/9b0e5f3fc87ae9ab9bbdfcf1b418d919"},"headline":"Google Ads: come selezionare parole chiave efficaci","datePublished":"2021-09-22T06:00:00+00:00","dateModified":"2025-03-07T08:36:20+00:00","mainEntityOfPage":{"@id":"https:\/\/www.italiaonline.it\/risorse\/google-ads-come-selezionare-parole-chiave-efficaci-4416"},"wordCount":1156,"image":{"@id":"https:\/\/www.italiaonline.it\/risorse\/google-ads-come-selezionare-parole-chiave-efficaci-4416#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaonline.it\/risorse\/wp-content\/uploads\/sites\/12\/2024\/04\/google-ads.jpg","keywords":["Articoli e news sulla pubblicit\u00e0 online"],"articleSection":["Blog","Pubblicit\u00e0 Online"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.italiaonline.it\/risorse\/google-ads-come-selezionare-parole-chiave-efficaci-4416","url":"https:\/\/www.italiaonline.it\/risorse\/google-ads-come-selezionare-parole-chiave-efficaci-4416","name":"Google Ads: come scegliere le parole chiave giuste | Italiaonline","isPartOf":{"@id":"https:\/\/www.italiaonline.it\/risorse\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaonline.it\/risorse\/google-ads-come-selezionare-parole-chiave-efficaci-4416#primaryimage"},"image":{"@id":"https:\/\/www.italiaonline.it\/risorse\/google-ads-come-selezionare-parole-chiave-efficaci-4416#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaonline.it\/risorse\/wp-content\/uploads\/sites\/12\/2024\/04\/google-ads.jpg","datePublished":"2021-09-22T06:00:00+00:00","dateModified":"2025-03-07T08:36:20+00:00","author":{"@id":"https:\/\/www.italiaonline.it\/risorse\/#\/schema\/person\/9b0e5f3fc87ae9ab9bbdfcf1b418d919"},"description":"Devi creare una campagna Google Ads? Scegliere le parole chiave giuste per il tuo annuncio \u00e8 fondamentale. Scopri di pi\u00f9 su Italiaonline.","breadcrumb":{"@id":"https:\/\/www.italiaonline.it\/risorse\/google-ads-come-selezionare-parole-chiave-efficaci-4416#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaonline.it\/risorse\/google-ads-come-selezionare-parole-chiave-efficaci-4416"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaonline.it\/risorse\/google-ads-come-selezionare-parole-chiave-efficaci-4416#primaryimage","url":"https:\/\/www.italiaonline.it\/risorse\/wp-content\/uploads\/sites\/12\/2024\/04\/google-ads.jpg","contentUrl":"https:\/\/www.italiaonline.it\/risorse\/wp-content\/uploads\/sites\/12\/2024\/04\/google-ads.jpg","width":1217,"height":694},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaonline.it\/risorse\/google-ads-come-selezionare-parole-chiave-efficaci-4416#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaonline.it\/risorse\/"},{"@type":"ListItem","position":2,"name":"Google Ads: come selezionare parole chiave efficaci"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaonline.it\/risorse\/#website","url":"https:\/\/www.italiaonline.it\/risorse\/","name":"Blog Italiaonline","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaonline.it\/risorse\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaonline.it\/risorse\/#\/schema\/person\/9b0e5f3fc87ae9ab9bbdfcf1b418d919","name":"Redazione Italiaonline","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaonline.it\/risorse\/wp-content\/uploads\/sites\/12\/2025\/03\/cropped-cropped-cropped-favicon-2-80x80-1.png","url":"https:\/\/www.italiaonline.it\/risorse\/wp-content\/uploads\/sites\/12\/2025\/03\/cropped-cropped-cropped-favicon-2-80x80-1.png","contentUrl":"https:\/\/www.italiaonline.it\/risorse\/wp-content\/uploads\/sites\/12\/2025\/03\/cropped-cropped-cropped-favicon-2-80x80-1.png","caption":"Redazione Italiaonline"},"description":"Italiaonline \u00e8 il partner delle imprese italiane nella trasformazione digitale e accompagna oltre 700 grandi imprese, 1.800 enti pubblici e 205 mila piccole e medie imprese. Con 45 sedi e quasi 700 consulenti, offre soluzioni per la presenza online, siti web, e-commerce, pubblicit\u00e0, gestione social e tanto altro. Attraverso le sue piattaforme digitali come PagineGialle, PagineGialle Casa, PagineGialle Shop e PagineBianche connette milioni di clienti con aziende e professionisti. I suoi portali, tra cui Libero e Virgilio, raggiungono oltre 25 milioni di utenti mensili. La concessionaria iOL Advertising supporta i principali operatori economici del Paese, Grandi Aziende e Centri Media, nello sviluppo delle loro campagne di comunicazione digitale.","url":"https:\/\/www.italiaonline.it\/risorse\/author\/redazione-italiaonline"}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/www.italiaonline.it\/risorse\/wp-json\/wp\/v2\/posts\/3050","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.italiaonline.it\/risorse\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaonline.it\/risorse\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaonline.it\/risorse\/wp-json\/wp\/v2\/users\/50"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaonline.it\/risorse\/wp-json\/wp\/v2\/comments?post=3050"}],"version-history":[{"count":3,"href":"https:\/\/www.italiaonline.it\/risorse\/wp-json\/wp\/v2\/posts\/3050\/revisions"}],"predecessor-version":[{"id":13377,"href":"https:\/\/www.italiaonline.it\/risorse\/wp-json\/wp\/v2\/posts\/3050\/revisions\/13377"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaonline.it\/risorse\/wp-json\/wp\/v2\/media\/1101"}],"wp:attachment":[{"href":"https:\/\/www.italiaonline.it\/risorse\/wp-json\/wp\/v2\/media?parent=3050"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaonline.it\/risorse\/wp-json\/wp\/v2\/categories?post=3050"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaonline.it\/risorse\/wp-json\/wp\/v2\/tags?post=3050"},{"taxonomy":"area-geografica","embeddable":true,"href":"https:\/\/www.italiaonline.it\/risorse\/wp-json\/wp\/v2\/area-geografica?post=3050"},{"taxonomy":"servizi-acquistati","embeddable":true,"href":"https:\/\/www.italiaonline.it\/risorse\/wp-json\/wp\/v2\/servizi-acquistati?post=3050"},{"taxonomy":"settore-merceologico","embeddable":true,"href":"https:\/\/www.italiaonline.it\/risorse\/wp-json\/wp\/v2\/settore-merceologico?post=3050"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}